{"id":2552,"date":"2020-10-01T03:23:47","date_gmt":"2020-10-01T06:23:47","guid":{"rendered":"http:\/\/vocesdebaires.com.ar\/wordpress\/index.php\/2020\/10\/01\/ciudad-secuestraron-cajas-de-medicamentos\/"},"modified":"2020-10-01T03:23:47","modified_gmt":"2020-10-01T06:23:47","slug":"ciudad-secuestraron-cajas-de-medicamentos","status":"publish","type":"post","link":"https:\/\/vocesdebaires.com.ar\/index.php\/2020\/10\/01\/ciudad-secuestraron-cajas-de-medicamentos\/","title":{"rendered":"Ciudad secuestraron cajas de medicamentos"},"content":{"rendered":"<p>Personal de la Divisi\u00f3n Delitos Contra la Salud de la Polic\u00eda de la Ciudad junto con la Agencia Gubernamental de Control (AGC) llevaron a cabo una inspecci\u00f3n en un estacionamiento de la avenida Pueyrred\u00f3n al 1.700, por almacenamiento de medicamentos sin las condiciones de higiene y mantenimiento necesarias. Al llegar al lugar, los efectivos corroboraron que un estacionamiento de cuatro niveles utilizaba tres pisos para el resguardo de gran cantidad de medicamentos e insumos m\u00e9dicos. Esta actividad se encuentra prohibida, ya que no cumple con las condiciones legales para su almacenamiento.Momentos despu\u00e9s, se confirm\u00f3 que eran visitadores m\u00e9dicos de distintos laboratorios los que guardaban los elementos en el lugar.<\/p>\n<p>Se hizo presente personal del Ministerio de Salud de la Naci\u00f3n, que realiz\u00f3 un relevamiento de las siete mil cajas de diversos laboratorios y ratific\u00f3 que los propietarios de los f\u00e1rmacos no respetaron la reglamentaci\u00f3n que regula el tratamiento, la guarda y disposici\u00f3n de los mismos para el consumo humano, por lo que si se pon\u00edan en circulaci\u00f3n podr\u00edan ser perjudiciales para el organismo humano. Por este motivo, la Fiscal\u00eda Penal Contravencional y de Faltas N\u00famero 12, a cargo del doctor Fedullo y ante la Secretar\u00eda de la doctora Cevasco, dispuso que se realice un muestreo de los medicamentos para determinar si est\u00e1n en condiciones de ser suministrados a los pacientes y, en el caso de ser aptos, que se distribuyan en los hospitales p\u00fablicos. Por su parte, el personal de la AGC procedi\u00f3 a la clausura del lugar, ya que contaba con una habilitaci\u00f3n ap\u00f3crifa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personal de la Divisi\u00f3n Delitos Contra la Salud de la Polic\u00eda de la Ciudad junto con la Agencia Gubernamental de Control (AGC) llevaron a cabo una inspecci\u00f3n en un estacionamiento de la avenida Pueyrred\u00f3n al 1.700, por almacenamiento de medicamentos sin las condiciones de higiene y mantenimiento necesarias. Al llegar al lugar, los efectivos corroboraron [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[11,32],"tags":[],"class_list":["post-2552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudad","category-comunas"],"_links":{"self":[{"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2552"}],"collection":[{"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2552"}],"version-history":[{"count":0,"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/2552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/media\/2553"}],"wp:attachment":[{"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vocesdebaires.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}